{"id":132,"date":"2018-09-24T11:54:46","date_gmt":"2018-09-24T09:54:46","guid":{"rendered":"http:\/\/wildtierfreund.de\/wordpress\/?p=132"},"modified":"2018-09-24T11:54:46","modified_gmt":"2018-09-24T09:54:46","slug":"so-klingt-die-heimische-tierwelt","status":"publish","type":"post","link":"https:\/\/www.wildtierfreund.de\/wordpress\/so-klingt-die-heimische-tierwelt\/","title":{"rendered":"So klingt die heimische Tierwelt"},"content":{"rendered":"<p>Wusstest Du, dass Rehe bellen? Und wie \u201ereden\u201c Feldhamster miteinander? Lachen Lachm\u00f6wen wirklich? Welche Ger\u00e4usche macht ein Seehund? Hast Du schon mal Flederm\u00e4use \u201eschmatzen\u201c geh\u00f6rt? Wie klingt es, wenn der Luchs faucht und der Storch klappert?<\/p>\n<p>Bei Wildtierfreund.de kannst Du Dir die Tiere unserer Landschaften jetzt nicht nur ansehen, sondern auch <strong>anh\u00f6ren<\/strong>. Die Tierportraits im Bereich \u201eForschen\u201c wurden mit Ton-Dateien erg\u00e4nzt. Klicke einfach auf den kleinen Lautsprecher und staune \u00fcber die vielf\u00e4ltigen Tierstimmen unserer Natur.<\/p>\n<p><a href=\"http:\/\/www.wildtierfreund.de\/forschen.html\">\u00a0\u00a0http:\/\/www.wildtierfreund.de\/forschen.html<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-133\" src=\"http:\/\/wildtierfreund.de\/wordpress\/wp-content\/uploads\/2018\/09\/Bildschirmfoto-2018-09-24-um-11.52.02.png\" alt=\"\" width=\"119\" height=\"85\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wusstest Du, dass Rehe bellen? Und wie \u201ereden\u201c Feldhamster miteinander? Lachen Lachm\u00f6wen wirklich? Welche Ger\u00e4usche macht ein Seehund? Hast Du schon mal Flederm\u00e4use \u201eschmatzen\u201c geh\u00f6rt? Wie klingt es, wenn der Luchs faucht und der Storch klappert? Bei Wildtierfreund.de kannst Du Dir die Tiere unserer Landschaften jetzt nicht nur ansehen, sondern auch anh\u00f6ren. Die Tierportraits im [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-132","post","type-post","status-publish","format-standard","hentry","category-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":2,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"predecessor-version":[{"id":135,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/132\/revisions\/135"}],"wp:attachment":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}