{"id":706,"date":"2025-07-09T10:09:41","date_gmt":"2025-07-09T08:09:41","guid":{"rendered":"https:\/\/www.wildtierfreund.de\/wordpress\/?p=706"},"modified":"2025-07-09T10:09:41","modified_gmt":"2025-07-09T08:09:41","slug":"werde-ein-tierspuren-detektiv","status":"publish","type":"post","link":"https:\/\/www.wildtierfreund.de\/wordpress\/werde-ein-tierspuren-detektiv\/","title":{"rendered":"Werde ein Tierspuren-Detektiv!"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1006\" height=\"697\" src=\"https:\/\/www.wildtierfreund.de\/wordpress\/wp-content\/uploads\/2025\/07\/Paula_2.png\" alt=\"Grafisches Bild mit einer F\u00f6rsterin mit Lupe, die im Wald steht. Daneben \u00e4st ein Hirsch und man erkennt Spuren auf dem Boden \" class=\"wp-image-728\" style=\"width:703px;height:auto\" srcset=\"https:\/\/www.wildtierfreund.de\/wordpress\/wp-content\/uploads\/2025\/07\/Paula_2.png 1006w, https:\/\/www.wildtierfreund.de\/wordpress\/wp-content\/uploads\/2025\/07\/Paula_2-300x208.png 300w, https:\/\/www.wildtierfreund.de\/wordpress\/wp-content\/uploads\/2025\/07\/Paula_2-150x104.png 150w\" sizes=\"auto, (max-width: 1006px) 100vw, 1006px\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Heute haben wir etwas ganz Besonderes f\u00fcr dich! Du kannst dich n\u00e4mlich von Wildtierfreund.de zum Tierspuren-Detektiv ausbilden lassen.<\/p>\n\n\n\n<p>Gemeinsam mit F\u00f6rsterin Paula entdeckst du verschiedene Tierspuren: Spuren am Boden, Fra\u00dfspuren und Losungen, also den Kot von Wildtieren. <\/p>\n\n\n\n<p>Wenn du das Abschluss-Quiz am Ende schaffst, darfst du dir deinen eigenen Tierspuren-Detektivausweis herunterladen! Und nicht nur das: In diesem <a href=\"https:\/\/kucobina.seitenstark.de\/play\/tierspuren#\/kapitel-0\/folie-1\">Themenpaket<\/a> stecken noch viele weitere Ideen, Anregungen und Aktionen rund um das Thema Spuren. <\/p>\n\n\n\n<p>Wir w\u00fcnschen dir viel Spa\u00df und Erfolg bei deiner Spurensuche!<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sp\u00fcrnasen aufgepasst! Gemeinsam mit F\u00f6rsterin Paula bildet dich Wildtierfreund.de zum Tierspuren-Detektiv und zur Tierspuren-Detektivin aus. Es geht um F\u00e4hrten, Fra\u00dfspuren und Losungen und am Ende bekommst du deinen ganz pers\u00f6nlichen Tierspuren-Detektivausweis.<\/p>\n","protected":false},"author":123460,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[40,304,305,109,303,113,26,33,302,171,80,301,106,107,300,8,108,95,10],"class_list":["post-706","post","type-post","status-publish","format-standard","hentry","category-neuigkeiten","tag-aktion","tag-detektiv","tag-detektivin","tag-faehrte","tag-frassspuren","tag-freizeit","tag-kinder","tag-lebensraum","tag-losung","tag-quiz","tag-raetsel","tag-spass","tag-spuren","tag-spurensuche","tag-tierspur","tag-tierspuren","tag-trittsiegel","tag-wildtier","tag-wildtiere"],"_links":{"self":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/users\/123460"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":2,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"predecessor-version":[{"id":730,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/posts\/706\/revisions\/730"}],"wp:attachment":[{"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildtierfreund.de\/wordpress\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}